{"id":207,"count":4,"description":"","link":"https:\/\/nimarent-backup.ziedoestesten.be\/nl\/assortiment\/tafel-servies\/porselein\/forest\/","name":"Forest","slug":"forest","taxonomy":"product_cat","parent":123,"meta":[],"menu_order":0,"acf":[],"_links":{"self":[{"href":"https:\/\/nimarent-backup.ziedoestesten.be\/nl\/wp-json\/wp\/v2\/product_cat\/207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nimarent-backup.ziedoestesten.be\/nl\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/nimarent-backup.ziedoestesten.be\/nl\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/nimarent-backup.ziedoestesten.be\/nl\/wp-json\/wp\/v2\/product_cat\/123"}],"wp:post_type":[{"href":"https:\/\/nimarent-backup.ziedoestesten.be\/nl\/wp-json\/wp\/v2\/product?product_cat=207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}