{"id":40911,"date":"2022-02-01T14:19:50","date_gmt":"2022-02-01T13:19:50","guid":{"rendered":"https:\/\/nimarent.be\/product\/assiette-creuse-brun-clair-22-cm\/"},"modified":"2026-06-09T19:48:38","modified_gmt":"2026-06-09T17:48:38","slug":"diep-bord-lichtbruin-d22cm","status":"publish","type":"product","link":"https:\/\/nimarent-backup.ziedoestesten.be\/nl\/aanbod\/tafel-servies\/porselein\/diep-bord-lichtbruin-d22cm\/diep-bord-lichtbruin-d22cm\/","title":{"rendered":"Diep Bord Lichtbruin 22 cm"},"content":{"rendered":"<p style=\"font-size: 0.8em; text-align: center;\">*Huurprijs per weekend (van donderdagmiddag tot maandagavond). Artikelen vuil terug.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>OPM:<br \/>\n* Bij een bestelling met een bedrag &lt; \u20ac 25 netto worden er \u20ac 2,5 orderkosten aangerekend.<br \/>\n* Ontbrekende en beschadigde\/gebroken artikelen worden aangerekend aan onze verkoopprijs die u op eenvoudig verzoek kan opvragen.<\/p>\n","protected":false},"featured_media":46868,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[123,122,125],"product_tag":[],"class_list":["post-40911","product","type-product","status-publish","has-post-thumbnail","product_cat-porselein","product_cat-tafel-servies","product_cat-walking-dinner","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/nimarent-backup.ziedoestesten.be\/nl\/wp-json\/wp\/v2\/product\/40911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nimarent-backup.ziedoestesten.be\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nimarent-backup.ziedoestesten.be\/nl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/nimarent-backup.ziedoestesten.be\/nl\/wp-json\/wp\/v2\/comments?post=40911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nimarent-backup.ziedoestesten.be\/nl\/wp-json\/wp\/v2\/media\/46868"}],"wp:attachment":[{"href":"https:\/\/nimarent-backup.ziedoestesten.be\/nl\/wp-json\/wp\/v2\/media?parent=40911"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nimarent-backup.ziedoestesten.be\/nl\/wp-json\/wp\/v2\/product_brand?post=40911"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nimarent-backup.ziedoestesten.be\/nl\/wp-json\/wp\/v2\/product_cat?post=40911"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nimarent-backup.ziedoestesten.be\/nl\/wp-json\/wp\/v2\/product_tag?post=40911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}