{"id":47620,"date":"2019-05-10T14:38:04","date_gmt":"2019-05-10T12:38:04","guid":{"rendered":"https:\/\/nimarent.be\/aanbod\/non class\u00e9\/cuillere-a-dessert-punto\/cuillere-a-dessert-punto\/"},"modified":"2019-05-10T14:38:04","modified_gmt":"2019-05-10T12:38:04","slug":"cuillere-a-dessert-punto","status":"publish","type":"product","link":"https:\/\/nimarent-backup.ziedoestesten.be\/fr\/gamme\/art-de-la-table\/couverts\/punto\/cuillere-a-dessert-punto\/cuillere-a-dessert-punto\/","title":{"rendered":"Cuill\u00e8re \u00e0 dessert Punto"},"content":{"rendered":"<p style=\"font-size: 0.8em; text-align: center;\">*Prix de location par week-end (du jeudi apr\u00e8s-midi au lundi soir). Articles retourn\u00e9s sales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>*Prix de location par week-end (du jeudi apr\u00e8s-midi au lundi soir). Articles retourn\u00e9s sales.<\/p>\n","protected":false},"featured_media":46521,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[348,349,356],"product_tag":[],"class_list":["post-47620","product","type-product","status-publish","has-post-thumbnail","product_cat-art-de-la-table","product_cat-couverts","product_cat-punto","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/nimarent-backup.ziedoestesten.be\/fr\/wp-json\/wp\/v2\/product\/47620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nimarent-backup.ziedoestesten.be\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/nimarent-backup.ziedoestesten.be\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/nimarent-backup.ziedoestesten.be\/fr\/wp-json\/wp\/v2\/comments?post=47620"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nimarent-backup.ziedoestesten.be\/fr\/wp-json\/wp\/v2\/media\/46521"}],"wp:attachment":[{"href":"https:\/\/nimarent-backup.ziedoestesten.be\/fr\/wp-json\/wp\/v2\/media?parent=47620"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/nimarent-backup.ziedoestesten.be\/fr\/wp-json\/wp\/v2\/product_brand?post=47620"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/nimarent-backup.ziedoestesten.be\/fr\/wp-json\/wp\/v2\/product_cat?post=47620"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/nimarent-backup.ziedoestesten.be\/fr\/wp-json\/wp\/v2\/product_tag?post=47620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}